{"id":15,"count":1,"description":"","link":"https:\/\/maxestate360gurgaon.co.in\/blog\/tag\/new-project-in-gurgaon\/","name":"New Project in Gurgaon","slug":"new-project-in-gurgaon","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>New Project in Gurgaon Archives - Max Estate 360 Gurgaon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maxestate360gurgaon.co.in\/blog\/tag\/new-project-in-gurgaon\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"New Project in Gurgaon Archives - Max Estate 360 Gurgaon\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maxestate360gurgaon.co.in\/blog\/tag\/new-project-in-gurgaon\/\" \/>\n<meta property=\"og:site_name\" content=\"Max Estate 360 Gurgaon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/maxestate360gurgaon.co.in\/blog\/tag\/new-project-in-gurgaon\/\",\"url\":\"https:\/\/maxestate360gurgaon.co.in\/blog\/tag\/new-project-in-gurgaon\/\",\"name\":\"New Project in Gurgaon Archives - Max Estate 360 Gurgaon\",\"isPartOf\":{\"@id\":\"https:\/\/maxestate360gurgaon.co.in\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/maxestate360gurgaon.co.in\/blog\/tag\/new-project-in-gurgaon\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/maxestate360gurgaon.co.in\/blog\/tag\/new-project-in-gurgaon\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/maxestate360gurgaon.co.in\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"New Project in Gurgaon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/maxestate360gurgaon.co.in\/blog\/#website\",\"url\":\"https:\/\/maxestate360gurgaon.co.in\/blog\/\",\"name\":\"Max Estate 360 Gurgaon\",\"description\":\"Luxury Flats in Sector 36a, Dwarka Expressway Gurgaon\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/maxestate360gurgaon.co.in\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"New Project in Gurgaon Archives - Max Estate 360 Gurgaon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maxestate360gurgaon.co.in\/blog\/tag\/new-project-in-gurgaon\/","og_locale":"en_US","og_type":"article","og_title":"New Project in Gurgaon Archives - Max Estate 360 Gurgaon","og_url":"https:\/\/maxestate360gurgaon.co.in\/blog\/tag\/new-project-in-gurgaon\/","og_site_name":"Max Estate 360 Gurgaon","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/maxestate360gurgaon.co.in\/blog\/tag\/new-project-in-gurgaon\/","url":"https:\/\/maxestate360gurgaon.co.in\/blog\/tag\/new-project-in-gurgaon\/","name":"New Project in Gurgaon Archives - Max Estate 360 Gurgaon","isPartOf":{"@id":"https:\/\/maxestate360gurgaon.co.in\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/maxestate360gurgaon.co.in\/blog\/tag\/new-project-in-gurgaon\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/maxestate360gurgaon.co.in\/blog\/tag\/new-project-in-gurgaon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/maxestate360gurgaon.co.in\/blog\/"},{"@type":"ListItem","position":2,"name":"New Project in Gurgaon"}]},{"@type":"WebSite","@id":"https:\/\/maxestate360gurgaon.co.in\/blog\/#website","url":"https:\/\/maxestate360gurgaon.co.in\/blog\/","name":"Max Estate 360 Gurgaon","description":"Luxury Flats in Sector 36a, Dwarka Expressway Gurgaon","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maxestate360gurgaon.co.in\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/maxestate360gurgaon.co.in\/blog\/wp-json\/wp\/v2\/tags\/15"}],"collection":[{"href":"https:\/\/maxestate360gurgaon.co.in\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/maxestate360gurgaon.co.in\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/maxestate360gurgaon.co.in\/blog\/wp-json\/wp\/v2\/posts?tags=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}